{"id":3551,"date":"2023-04-24T15:17:46","date_gmt":"2023-04-24T13:17:46","guid":{"rendered":"https:\/\/passdeck.de\/wp-content\/uploads\/2023\/04\/book.json"},"modified":"2023-04-24T15:17:46","modified_gmt":"2023-04-24T13:17:46","slug":"book","status":"inherit","type":"attachment","link":"https:\/\/passdeck.de\/de\/folienmaster\/book\/","title":{"rendered":"book"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-3551","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>book - PassDeck<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/passdeck.de\/wp-content\/uploads\/2023\/04\/book.json\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"book - PassDeck\" \/>\n<meta property=\"og:description\" content=\"book\" \/>\n<meta property=\"og:url\" content=\"https:\/\/passdeck.de\/wp-content\/uploads\/2023\/04\/book.json\" \/>\n<meta property=\"og:site_name\" content=\"PassDeck\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/passdeck\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/passdeck.de\/wp-content\/uploads\/2023\/01\/back_passdeck_home-2023.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/passdeck.de\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/book.json\",\"url\":\"https:\\\/\\\/passdeck.de\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/book.json\",\"name\":\"book - PassDeck\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/passdeck.de\\\/#website\"},\"datePublished\":\"2023-04-24T13:17:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/passdeck.de\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/book.json#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/passdeck.de\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/book.json\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/passdeck.de\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/book.json#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/passdeck.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Folienmaster\",\"item\":\"https:\\\/\\\/passdeck.de\\\/de\\\/folienmaster\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"book\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/passdeck.de\\\/#website\",\"url\":\"https:\\\/\\\/passdeck.de\\\/\",\"name\":\"PassDeck\",\"description\":\"Where slides win deals.\",\"publisher\":{\"@id\":\"https:\\\/\\\/passdeck.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/passdeck.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/passdeck.de\\\/#organization\",\"name\":\"PassDeck\",\"url\":\"https:\\\/\\\/passdeck.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/passdeck.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/passdeck.de\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cropped-Linkedin_logo-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/passdeck.de\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cropped-Linkedin_logo-scaled-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"PassDeck\"},\"image\":{\"@id\":\"https:\\\/\\\/passdeck.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/passdeck\\\/\",\"https:\\\/\\\/www.instagram.com\\\/passdeck.de\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/passdeck\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"book - PassDeck","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/passdeck.de\/wp-content\/uploads\/2023\/04\/book.json","og_locale":"de_DE","og_type":"article","og_title":"book - PassDeck","og_description":"book","og_url":"https:\/\/passdeck.de\/wp-content\/uploads\/2023\/04\/book.json","og_site_name":"PassDeck","article_publisher":"https:\/\/www.facebook.com\/passdeck\/","og_image":[{"width":1920,"height":1200,"url":"https:\/\/passdeck.de\/wp-content\/uploads\/2023\/01\/back_passdeck_home-2023.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/passdeck.de\/wp-content\/uploads\/2023\/04\/book.json","url":"https:\/\/passdeck.de\/wp-content\/uploads\/2023\/04\/book.json","name":"book - PassDeck","isPartOf":{"@id":"https:\/\/passdeck.de\/#website"},"datePublished":"2023-04-24T13:17:46+00:00","breadcrumb":{"@id":"https:\/\/passdeck.de\/wp-content\/uploads\/2023\/04\/book.json#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/passdeck.de\/wp-content\/uploads\/2023\/04\/book.json"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/passdeck.de\/wp-content\/uploads\/2023\/04\/book.json#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/passdeck.de\/de\/"},{"@type":"ListItem","position":2,"name":"Folienmaster","item":"https:\/\/passdeck.de\/de\/folienmaster\/"},{"@type":"ListItem","position":3,"name":"book"}]},{"@type":"WebSite","@id":"https:\/\/passdeck.de\/#website","url":"https:\/\/passdeck.de\/","name":"PassDeck","description":"Where slides win deals.","publisher":{"@id":"https:\/\/passdeck.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/passdeck.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/passdeck.de\/#organization","name":"PassDeck","url":"https:\/\/passdeck.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/passdeck.de\/#\/schema\/logo\/image\/","url":"https:\/\/passdeck.de\/wp-content\/uploads\/2022\/08\/cropped-Linkedin_logo-scaled-1.jpg","contentUrl":"https:\/\/passdeck.de\/wp-content\/uploads\/2022\/08\/cropped-Linkedin_logo-scaled-1.jpg","width":512,"height":512,"caption":"PassDeck"},"image":{"@id":"https:\/\/passdeck.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/passdeck\/","https:\/\/www.instagram.com\/passdeck.de\/","https:\/\/www.linkedin.com\/company\/passdeck"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/passdeck.de\/wp-content\/uploads\/2023\/04\/book.json'>book<\/a><\/p>\n"},"caption":{"rendered":"<p>book<\/p>\n"},"alt_text":"","media_type":"file","mime_type":"application\/json","media_details":{"filesize":44016,"sizes":{}},"post":3546,"source_url":"https:\/\/passdeck.de\/wp-content\/uploads\/2023\/04\/book.json","filename":"book.json","filesize":44016,"_links":{"self":[{"href":"https:\/\/passdeck.de\/de\/wp-json\/wp\/v2\/media\/3551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/passdeck.de\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/passdeck.de\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/passdeck.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/passdeck.de\/de\/wp-json\/wp\/v2\/comments?post=3551"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":3546,"href":"https:\/\/passdeck.de\/de\/wp-json\/wp\/v2\/pages\/3546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}